{"id":143,"date":"2008-04-18T23:42:26","date_gmt":"2008-04-18T21:42:26","guid":{"rendered":"http:\/\/www.streetlightstv.de\/blog\/das-corporate-design-als-teil-der-streetlightstv-corporate-identity\/"},"modified":"2008-04-19T00:06:48","modified_gmt":"2008-04-18T22:06:48","slug":"das-corporate-design-als-teil-der-streetlightstv-corporate-identity","status":"publish","type":"post","link":"http:\/\/www.streetlightstv.de\/blog\/das-corporate-design-als-teil-der-streetlightstv-corporate-identity\/","title":{"rendered":"Das Corporate Design als Teil der StreetLightsTV-Corporate-Identity"},"content":{"rendered":"<p>So, wie ihr seht, hat sich der Blog heute von Beige in Schwarz gewandelt. Warum das so ist, ist ganz einfach erkl&#228;rt: Seit einigen Tagen bin ich dabei die Videoblog-Seite von <a href=\" http:\/\/www.streetlightstv.de \">StreetLightsTV<\/a>, auf der ab Mai die einzelnen Folgen unserer Doku-Serie \u201eausgestrahlt\u201c werden sollen, zu entwerfen. Dabei habe ich mich vom Aussehen her an dem von uns definierten <a href=\" http:\/\/de.wikipedia.org\/wiki\/Corporate_Design\">Corporate Design (CD)<\/a> orientiert: Wei&#223;, Grau und wie ihr seht auch Schwarz als elementarer Farbe.<\/p>\n<p><strong>Einheitliches Auftreten<\/strong><\/p>\n<p><a href=\" http:\/\/www.streetlightstv.de\/blog\/\"><center><img decoding=\"async\" src=\" http:\/\/www.streetlightstv.de\/blog\/wp-content\/myfotos\/ohnegalerie\/cd_sltv-blog.jpg\" \/><\/center><\/a><\/p>\n<p>Doch nicht nur der <a href=\" http:\/\/www.streetlightstv.de\/blog\/\">StreetLightsTV-Blog<\/a> hat seine Farbe ge&#228;ndert, auch das <a href=\" http:\/\/www.streetlightstv.de\/presse-center\/ \">SLTV-Presse-Center<\/a> wurde an das CD angepasst und dementsprechend in schwarz geh&#252;llt. Und was f&#252;r den Internetauftritt von StreetLightsTV gilt, das betrifft in Zukunft auch alle weiteren Produkte, die im Zusammenhang mit StreetLightsTV entworfen werden. Ob es nun um Flyer, Banner oder eventuell auch Merchandising geht, immer wird die Farbe Schwarz tonangebend sein und von Grau und Wei&#223; unterst&#252;tzt werden!<\/p>\n<p><strong>Unsere Identit&#228;t<\/strong><\/p>\n<p><a href=\" http:\/\/www.streetlightstv.de\/presse-center\/\"><center><img decoding=\"async\" src=\" http:\/\/www.streetlightstv.de\/blog\/wp-content\/myfotos\/ohnegalerie\/cd_sltv-pc.jpg\" \/><\/center><\/a><\/p>\n<p>Ziel des Corporate Design, seinerseits wiederum Teil der <a href=\" http:\/\/de.wikipedia.org\/wiki\/Corporate_Identity\">Corporate Identity<\/a>,  ist es, eine einheitliche visuelle Identit&#228;t f&#252;r <a href=\" http:\/\/www.streetlightstv.de \">StreetLightsTV<\/a> zu schaffen. Dabei sind die Farben Schwarz, Wei&#223; und Grau als elementare Bestandteile anzusehen, die zusammen mit der verwendeten Schriftart SKYfontThick nicht nur f&#252;r ein einheitliches Auftreten, sondern auch f&#252;r einen guten Wiedererkennungswert sorgen sollen.<\/p>\n<p>Ach ja, wer sich f&#252;r die <a href=\" http:\/\/de.wikipedia.org\/wiki\/Corporate_Behaviour\">Corporate Behaviour<\/a> von <a href=\" http:\/\/www.streetlightstv.de\/\">StreetLightsTV<\/a> interessieren sollte, dem empfehle ich einen Blick in den <a href=\" http:\/\/www.streetlightstv.de\/blog\/sltv-team-session-presse-foto-shooting\/ \">Artikel &#252;ber unser Fotoshooting<\/a> zu werfen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>So, wie ihr seht, hat sich der Blog heute von Beige in Schwarz gewandelt. Warum das so ist, ist ganz einfach erkl&#228;rt: Seit einigen Tagen bin ich dabei die Videoblog-Seite von StreetLightsTV, auf der ab Mai die einzelnen Folgen unserer Doku-Serie \u201eausgestrahlt\u201c werden sollen, zu entwerfen. Dabei habe ich mich vom Aussehen her an dem [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[80,31,28],"_links":{"self":[{"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/posts\/143"}],"collection":[{"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/comments?post=143"}],"version-history":[{"count":0,"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/posts\/143\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/media?parent=143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/categories?post=143"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/tags?post=143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}