{"id":30,"date":"2007-12-26T20:46:34","date_gmt":"2007-12-26T19:46:34","guid":{"rendered":"http:\/\/www.streetlightstv.de\/blog\/die-texte\/folge-mainz\/"},"modified":"2008-04-15T02:20:19","modified_gmt":"2008-04-15T00:20:19","slug":"folge-mainz","status":"publish","type":"page","link":"http:\/\/www.streetlightstv.de\/blog\/die-texte\/folge-mainz\/","title":{"rendered":"&#8211; Folge: Mainz"},"content":{"rendered":"<p><strong>Folge Mainz: Brennpunkt Goetheplatz &#8211; Die Gedanken einer Streetworkerin und \u201eJugendliche auf der Stra&#223;e\u201c<\/strong><br \/>\n<br \/>\nNach dem Dreh von Folge #1 &#252;ber die <a href=\" http:\/\/www.streetlightstv.de\/blog\/die-texte\/folge-erfurt\/\" >Graffiti-Szene in Erfurt<\/a> haben wir etwa eine Woche sp&#228;ter die Folgen Nummer zwei, drei und vier im Rhein-Main-Gebiet gedreht. Dies hat sich insbesondere deswegen angeboten, da dort mit Mainz, Wiesbaden und Frankfurt insgesamt drei deutsche Gro&#223;st&#228;dte auf einem Haufen liegen, die gut und g&#252;nstig voneinander zu erreichen sind. Ein wichtiger Punkt f&#252;r unsere nahezu budgetlose Doku-Produktion!<br \/>\n<br \/>\nIn Folge #2 haben wir uns der Stadt Mainz gewidmet. Dabei dreht sich alles um das Thema Jugendliche auf der Stra&#223;e. Hierf&#252;r wurden neben etlichen Stadtbild-Aufnahmen verschiedene Interviews durchgef&#252;hrt. Zum einen mit einer Streetworkerin des Jugendamtes und zum anderen mit ausl&#228;ndischen Jugendlichen, die von dieser betreut werden und in letzter Zeit f&#252;r einige Aufregung in Mainz-Neustadt gesorgt haben.<br \/>\n<br \/>\n<img decoding=\"async\" src=\" http:\/\/www.bluejax.net\/wp-content\/themes\/northern-web-coders\/images\/Inhalt\/Medienprojekt\/2_jugendliche_mainz.jpg\"  border=\"0\"\/><br \/>\n<br \/>\n<strong>Eine Tages-Reise in den Westen<\/strong><br \/>\n<br \/>\nNachdem wir am Mittwoch, den 05. Dezember nahezu den halben Tag lang mit Z&#252;gen, S-Bahnen und Mitfahrgelegenheit aus Ilmenau unterwegs waren, mussten wir den Drehbeginn auf den darauf folgenden Donnerstag verschieben. An diesem stand dann das Einfangen des Mainzer Stadtbildes an.<br \/>\n<br \/>\nVon fr&#252;h morgens bis in die Dunkelheit liefen also Imke, Mario und ich quer durch die Stadt, um die bekanntesten Ecken und Sehensw&#252;rdigkeiten zu filmen. Der Fassnachtsbrunnen am Schillerplatz geh&#246;rte dabei genauso dazu, wie der Mainzer Dom, die Altstadt oder die Uferpromenade am Rhein.<br \/>\n<br \/>\n<strong>Jugendliche Sprayer in der Ruhmes-Halle<\/strong><br \/>\n<br \/>\nDanach ging es noch zur Graffiti-Hall-Of-Fame in Mainz-Kastel (ich wei&#223;, offiziell Wiesbaden\u2026), wo wir uns begeistert die wirklich beeindruckenden Kunstarbeiten der Mainzer Sprayer anschauten. Als wir ein paar Jugendliche beim sprayen sahen, sprachen wir diese spontan an und duften sie bei ihrer Arbeit filmen. Im Anschluss daran folgte ein improvisiertes Kurzinterview mit den Teenagern, die allerdings aufgrund ihres Alters nur unkenntlich aufgenommen werden durften.<br \/>\n<br \/>\nWeiter ging es dann erst wieder am Freitag. Nachdem wir vormittags mehrere Interview-Termine in Wiesbaden zur dortigen Folge hatten (Artikel folgt), hatten wir gegen 14.30 Uhr ein Treffen mit der Mainzer Streetworkerin Doreen. W&#228;hrend des Vorgespr&#228;ches, das wir im Aufenthaltsraum neben Doreens B&#252;ro f&#252;hrten, stellte sich ziemlich schnell heraus, dass es ein interessantes Interview werden k&#246;nnte.<br \/>\n<br \/>\n<strong>Die Arbeit einer Streetworkerin<\/strong><br \/>\n<br \/>\nBei Mainz hatten wir uns das Thema \u201eJugendliche auf der Stra&#223;e\u201c ausgesucht und waren damit bei Doreen genau richtig. Sie erz&#228;hlte uns von Jugendlichen Banden, die am Goetheplatz in Mainz-Neustadt von ihr betreut w&#252;rden und wie es dort in der vergangenen Zeit vermehrt zu Problemen und Auseinandersetzungen gekommen sei.<\/p>\n<p>Daraufhin entschlossen wir uns, das Interview aus der B&#252;ro-Umgebung nach drau&#223;en zu verlegen und direkt am \u201eBrennpunkt Goetheplatz\u201c zu drehen. Gl&#252;cklicherweise war dieses Mal mein Bruder Marcy, der an der Mainzer Universit&#228;t P&#228;dagogik studiert, mit von der Partie, so dass er uns den Ton angeln konnte. Ansonsten war es dieselbe Rollenverteilung wie bereits in Erfurt: Mario bediente die XL1-Kamera und Imke die handliche Sony. Ich selber f&#252;hrte in bekannter \u201e&#196;hm- und &#196;h-Manier\u201c das Interview durch.<br \/>\n<br \/>\n<strong>Interesse an der Sicht der Teenager<\/strong><br \/>\n<br \/>\nDoreen erz&#228;hlte uns in dem Gespr&#228;ch von ihrer Arbeit als Streetworkerin in Mainz und wie sie zu diesem Beruf gekommen ist. Au&#223;erdem sprach sie auch die bereits im Vorgespr&#228;ch diskutierte Sachlage am Goetheplatz an, berichtete von brennenden M&#252;lltonnen und perspektivlosen Jugendlichen, die f&#252;r einigen &#196;rger sorgten.<br \/>\n<br \/>\nNach den Aufnahmen teilte uns die Streetworkerin mit, dass sie hoffe, dass wir auch noch ein paar Interviews mit den Jugendlichen machen w&#252;rden. Sie selber w&#228;re sehr interessiert an den Aussagen und Statements, die diese uns eventuell geben k&#246;nnten. Ihrer Meinung nach, k&#246;nnten die Jugendlichen in einem Gespr&#228;ch mit uns vielleicht mehr offenbaren, als sie es vor offiziellen Betreuern wom&#246;glich taten.<br \/>\n<br \/>\n<strong>Das Gespr&#228;ch mit den Jugendlichen<\/strong><br \/>\n<br \/>\nDazu kamen wir aufgrund der Drehs und Interviews in Frankfurt und Wiesbaden erst wieder am Sonntagnachmittag. Abermals zogen wir mit unserer Ausr&#252;stung zum Goetheplatz in Mainz. Diesmal hatte Marcy leider keine Zeit, so dass ich den Ton w&#228;hrend des Interviews selber abnehmen musste.<br \/>\n<br \/>\nWie erwartet trafen wir etliche Jugendliche am Goetheplatz an. Diese zeigten sich auch gleich begeistert bei der M&#246;glichkeit von uns befragt und gefilmt zu werden. Nach einigen Diskussionen hatten wir den ersten Gespr&#228;chspartner ausfindig gemacht. Der 16-j&#228;hrige Hamlet zog mit uns etwas abseits und stellte sich unseren Fragen.<br \/>\n<br \/>\n<strong>Zwischen Gruppenzwang und individuellen Tr&#228;umen<\/strong><br \/>\n<br \/>\nSchnell folgte die restliche Clique und versammelte sich rund um uns herum. Erst als Imke und Mario die Kameras f&#252;r einen Moment abschalteten und damit drohten, die Interviews bleiben zu lassen und auch Hamlet auf seine Freunde einredete, zogen diese wieder ab und wir konnten ein interessantes Interview mit dem Jugendlichen aufzeichnen.<br \/>\n<br \/>\nDanach folgte der 14-j&#228;hrige Siar, der ebenfalls einen guten Einblick in das Leben der Jugendliche offenbarte. Ebenso wie Hamlet erz&#228;hlte auch er uns von seinem Alltag, von seinen Tr&#228;umen und W&#252;nschen. Etwas selbstkritisch gestand er ein, dass es der Gruppenzwang nicht einfach mache, aus der Konfliktspirale des Goetheplatzes herauszukommen. Richtig aufbl&#252;hen tat Siar, als er uns von seinem gro&#223;en Idol Bushido und seinem Traum einmal ein gro&#223;er Rapper zu werden, erz&#228;hlte.<br \/>\n<br \/>\n<strong>Unterschiedliche Perspektiven<\/strong><br \/>\n<br \/>\nAls es dann bereits begann zu d&#228;mmern, f&#252;hrten wir noch ein Doppelinterview mit Volkan und Esat durch. Auch hier kann man sagen, dass es ein sehr interessantes Interview war. W&#228;hrend der eine vollj&#228;hrig und in einer festen Ausbildung steckte, hatte der andere noch keine genauen Vorstellungen &#252;ber seine Zukunft und Ziele. Abermals erz&#228;hlten auch diese beiden Jungs uns von ihrem Leben, den Ereignissen auf der Stra&#223;e und den Problemen, die damit einhergehen.<br \/>\n<br \/>\nAlles in allem waren es drei sehr interessante Gespr&#228;che mit den vier Jugendlichen. Wir bekamen einige aufschlussreiche Einblicke in ihre Gedankenwelt und ihr Leben. Gleichzeitig erfuhren wir, dass Doreen bei den Jungs einen sehr guten Ruf zu genie&#223;en scheint. Nicht zuletzt diese Feststellung zeigt, wie enorm wichtig es ist, sich intensiv mit Jugendlichen auf der Stra&#223;e zu besch&#228;ftigen. Was nun noch fehlt ist die Einverst&#228;ndniserkl&#228;rung der Eltern der befragten Jugendlichen, damit wir das Material auch verwenden und publizieren d&#252;rfen!<br \/>\n<br \/>\n<strong>Zuh&#246;ren, Fragen, Hinterfragen<\/strong><br \/>\n<br \/>\nInteressant ist es, sich verschiedene Seiten zu einem Thema anzuh&#246;ren. Oftmals zeigt sich erst dadurch, wie komplex und hintergr&#252;ndig scheinbar einfache Probleme und Sachverhalte in Wirklichkeit doch sind. Umst&#228;nde, die wir in der Folge #2 &#252;ber Mainz versuchen darzustellen!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Folge Mainz: Brennpunkt Goetheplatz &#8211; Die Gedanken einer Streetworkerin und \u201eJugendliche auf der Stra&#223;e\u201c Nach dem Dreh von Folge #1 &#252;ber die Graffiti-Szene in Erfurt haben wir etwa eine Woche sp&#228;ter die Folgen Nummer zwei, drei und vier im Rhein-Main-Gebiet gedreht. Dies hat sich insbesondere deswegen angeboten, da dort mit Mainz, Wiesbaden und Frankfurt insgesamt [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":28,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"_links":{"self":[{"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/pages\/30"}],"collection":[{"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/comments?post=30"}],"version-history":[{"count":0,"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/pages\/30\/revisions"}],"up":[{"embeddable":true,"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/pages\/28"}],"wp:attachment":[{"href":"http:\/\/www.streetlightstv.de\/blog\/wp-json\/wp\/v2\/media?parent=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}